{"id":6116,"date":"2025-01-17T14:47:04","date_gmt":"2025-01-17T14:47:04","guid":{"rendered":"https:\/\/ariktools.com\/?page_id=6116"},"modified":"2025-02-21T15:59:41","modified_gmt":"2025-02-21T15:59:41","slug":"why-choose-us","status":"publish","type":"page","link":"https:\/\/ariktools.com\/pt\/why-choose-us\/","title":{"rendered":"Por que nos escolher"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6116\" class=\"elementor elementor-6116\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e5554b1 e-flex e-con-boxed e-con e-parent\" data-id=\"6e5554b1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f6c2b33 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"1f6c2b33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Como fabricante de ferramentas l\u00edder do setor, a Arik \u00e9 especializada em fornecer solu\u00e7\u00f5es personalizadas e de alta qualidade para o setor de constru\u00e7\u00e3o, empreiteiros de instala\u00e7\u00e3o de pisos e atacadistas. Entendemos os desafios exclusivos de cada projeto e sempre colocamos as necessidades do cliente no centro, fornecendo as ferramentas e os servi\u00e7os mais adequados para cada local de trabalho. Seja qual for a sua necessidade de opera\u00e7\u00f5es eficientes, ferramentas personalizadas ou entrega pontual, a Arik est\u00e1 aqui para oferecer suporte confi\u00e1vel.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2373aca5 e-flex e-con-boxed e-con e-parent\" data-id=\"2373aca5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-152cd850 e-con-full e-flex e-con e-child\" data-id=\"152cd850\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f9b75fb elementor-widget elementor-widget-image\" data-id=\"5f9b75fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"350\" height=\"235\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-High-Quality-and-Durability-1.png\" class=\"attachment-large size-large wp-image-6355\" alt=\"\" srcset=\"https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-High-Quality-and-Durability-1.png 350w, https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-High-Quality-and-Durability-1-300x201.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27a1f962 elementor-widget elementor-widget-heading\" data-id=\"27a1f962\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">1. Alta qualidade e durabilidade<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dc63297 elementor-widget elementor-widget-text-editor\" data-id=\"7dc63297\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Cada uma de nossas ferramentas passa por rigorosos controles de qualidade e \u00e9 fabricada com mat\u00e9rias-primas de primeira qualidade e t\u00e9cnicas avan\u00e7adas de fabrica\u00e7\u00e3o para garantir alto desempenho e durabilidade em uma variedade de locais de trabalho complexos. Quer voc\u00ea seja um empreiteiro comercial ou uma empresa de constru\u00e7\u00e3o, nossas ferramentas s\u00e3o excelentes para melhorar a efici\u00eancia do trabalho e reduzir os custos de manuten\u00e7\u00e3o.<\/p><ul><li><strong>Uso a longo prazo com confian\u00e7a<\/strong>: Cada ferramenta \u00e9 projetada para suportar o uso prolongado e intenso, reduzindo a necessidade de substitui\u00e7\u00f5es frequentes.<\/li><li><strong>Opera\u00e7\u00f5es eficientes<\/strong>: Projetado para um trabalho r\u00e1pido e eficiente, reduzindo as horas de trabalho e os custos gerais.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cc8 e-con-full e-flex e-con e-child\" data-id=\"cc8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b919fd7 elementor-widget elementor-widget-image\" data-id=\"3b919fd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"350\" height=\"235\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-Flexible-Customization-Services-2.png\" class=\"attachment-large size-large wp-image-6356\" alt=\"\" srcset=\"https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-Flexible-Customization-Services-2.png 350w, https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-Flexible-Customization-Services-2-300x201.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c2bd0c4 elementor-widget elementor-widget-heading\" data-id=\"7c2bd0c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">2. Servi\u00e7os de personaliza\u00e7\u00e3o flex\u00edveis\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c530cf6 elementor-widget elementor-widget-text-editor\" data-id=\"5c530cf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Cada projeto tem necessidades diferentes, e a Arik oferece servi\u00e7os flex\u00edveis de OEM e ODM para projetar e fabricar solu\u00e7\u00f5es personalizadas com base em requisitos espec\u00edficos. Fornecemos solu\u00e7\u00f5es sob medida para ajudar a melhorar a efici\u00eancia do projeto, adaptadas \u00e0s condi\u00e7\u00f5es exclusivas de cada canteiro de obras.<\/p><ul><li><strong>Ferramentas personalizadas<\/strong>: Seja para fun\u00e7\u00f5es, tamanhos ou ferramentas espec\u00edficas para necessidades particulares do local de trabalho, oferecemos servi\u00e7os de personaliza\u00e7\u00e3o profissional.<\/li><li><strong>Versatilidade em v\u00e1rios cen\u00e1rios de constru\u00e7\u00e3o<\/strong>: As ferramentas s\u00e3o especialmente projetadas para atender \u00e0s demandas de diferentes tipos de projetos, garantindo opera\u00e7\u00f5es tranquilas em qualquer local de trabalho.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b8a1db8 e-con-full e-flex e-con e-child\" data-id=\"5b8a1db8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4dfa7e9b elementor-widget elementor-widget-image\" data-id=\"4dfa7e9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"350\" height=\"235\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-On-Time-Delivery-to-Ensure-Project-Progress-3.png\" class=\"attachment-large size-large wp-image-6357\" alt=\"\" srcset=\"https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-On-Time-Delivery-to-Ensure-Project-Progress-3.png 350w, https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-On-Time-Delivery-to-Ensure-Project-Progress-3-300x201.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66032d82 elementor-widget elementor-widget-heading\" data-id=\"66032d82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">3. Entrega no prazo para garantir o andamento do projeto\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57c2329b elementor-widget elementor-widget-text-editor\" data-id=\"57c2329b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Entendemos que os projetos de constru\u00e7\u00e3o geralmente t\u00eam cronogramas r\u00edgidos, e \u00e9 por isso que priorizamos a entrega pontual e o gerenciamento de log\u00edstica. Ao otimizar os processos de produ\u00e7\u00e3o e trabalhar em estreita colabora\u00e7\u00e3o com as equipes de log\u00edstica, garantimos que todos os pedidos sejam entregues no prazo, para que seus projetos nunca sofram atrasos devido a problemas com ferramentas.<\/p><ul><li><strong>Entrega pontual para minimizar o tempo de espera<\/strong>: Garantimos a entrega no prazo para assegurar que seus projetos n\u00e3o sejam atrasados por problemas relacionados \u00e0 ferramenta.<\/li><li><strong>Gerenciamento eficiente da log\u00edstica<\/strong>: Oferecemos solu\u00e7\u00f5es de transporte convenientes para garantir que as ferramentas cheguem com rapidez e seguran\u00e7a ao seu local de trabalho.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-58d52b3 e-flex e-con-boxed e-con e-parent\" data-id=\"58d52b3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-237f78d e-con-full e-flex e-con e-child\" data-id=\"237f78d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b12ea99 elementor-widget elementor-widget-image\" data-id=\"b12ea99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"235\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-Professional-Technical-Support-and-After-Sales-Service-4.png\" class=\"attachment-large size-large wp-image-6358\" alt=\"\" srcset=\"https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-Professional-Technical-Support-and-After-Sales-Service-4.png 350w, https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-Professional-Technical-Support-and-After-Sales-Service-4-300x201.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-550f718 elementor-widget elementor-widget-heading\" data-id=\"550f718\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">4. Suporte t\u00e9cnico profissional e servi\u00e7o p\u00f3s-venda<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0478adc elementor-widget elementor-widget-text-editor\" data-id=\"0478adc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Como fabricante com anos de experi\u00eancia no setor, a Arik oferece suporte t\u00e9cnico e servi\u00e7os p\u00f3s-venda abrangentes. Nossos clientes n\u00e3o apenas recebem ferramentas de alta qualidade, mas tamb\u00e9m desfrutam de um s\u00f3lido suporte t\u00e9cnico e assist\u00eancia p\u00f3s-venda imediata, garantindo um desempenho est\u00e1vel das ferramentas durante os projetos e a r\u00e1pida resolu\u00e7\u00e3o de quaisquer problemas.<\/p><ul><li><strong>Suporte t\u00e9cnico<\/strong>: Oferecemos consultas e orienta\u00e7\u00f5es de especialistas para ajud\u00e1-lo a escolher e usar as ferramentas certas.<\/li><li><strong>Garantia p\u00f3s-venda<\/strong>: Nossa equipe de p\u00f3s-vendas est\u00e1 sempre dispon\u00edvel para prestar assist\u00eancia durante o uso da ferramenta, garantindo que seu projeto seja executado sem problemas.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6583726 e-con-full e-flex e-con e-child\" data-id=\"6583726\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9c5533 elementor-widget elementor-widget-image\" data-id=\"f9c5533\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"235\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-Cost-Effectiveness-and-Competitive-Pricing-5.png\" class=\"attachment-large size-large wp-image-6359\" alt=\"\" srcset=\"https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-Cost-Effectiveness-and-Competitive-Pricing-5.png 350w, https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-Cost-Effectiveness-and-Competitive-Pricing-5-300x201.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7216ef elementor-widget elementor-widget-heading\" data-id=\"e7216ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">5. Custo-efetividade e pre\u00e7os competitivos\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fca3c1c elementor-widget elementor-widget-text-editor\" data-id=\"fca3c1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Temos o compromisso de fornecer ferramentas de alta qualidade a pre\u00e7os competitivos. Seja voc\u00ea um atacadista, distribuidor ou empresa de constru\u00e7\u00e3o, oferecemos estrat\u00e9gias de pre\u00e7os flex\u00edveis que o ajudam a manter-se competitivo no mercado e a reduzir os custos do projeto.<\/p><ul><li><strong>Descontos para compras em massa<\/strong>: Oferecemos pre\u00e7os melhores para pedidos em grande escala, ajudando voc\u00ea a economizar nos custos de aquisi\u00e7\u00e3o.<\/li><li><strong>Estrutura de custos otimizada<\/strong>: Ao melhorar o desempenho e a durabilidade das ferramentas, ajudamos os clientes a reduzir os custos de manuten\u00e7\u00e3o e substitui\u00e7\u00e3o.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b209b0 e-con-full e-flex e-con e-child\" data-id=\"9b209b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5260386 elementor-widget elementor-widget-image\" data-id=\"5260386\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"235\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-Safety-and-Ease-of-Use-6.png\" class=\"attachment-large size-large wp-image-6360\" alt=\"\" srcset=\"https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-Safety-and-Ease-of-Use-6.png 350w, https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/ARIK-Safety-and-Ease-of-Use-6-300x201.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2de0dfc elementor-widget elementor-widget-heading\" data-id=\"2de0dfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">6. Seguran\u00e7a e facilidade de uso\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2aabd0a elementor-widget elementor-widget-text-editor\" data-id=\"2aabd0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>A seguran\u00e7a \u00e9 fundamental para os gerentes de canteiros de obras, e todas as ferramentas da Arik passam por rigorosos testes de seguran\u00e7a para atender aos mais altos padr\u00f5es. Tamb\u00e9m priorizamos a facilidade de uso em nossos projetos, garantindo que os funcion\u00e1rios no local possam dominar rapidamente as ferramentas e minimizar o tempo de treinamento.<\/p><ul><li><strong>Seguran\u00e7a em primeiro lugar<\/strong>: Todas as ferramentas est\u00e3o em conformidade com os padr\u00f5es internacionais de seguran\u00e7a, reduzindo os riscos no local de trabalho.<\/li><li><strong>F\u00e1cil de usar e r\u00e1pido de dominar<\/strong>: Projetos simples reduzem a dificuldade operacional e o tempo de treinamento, garantindo que as ferramentas estejam prontas para uso mais rapidamente.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c7fcae4 e-flex e-con-boxed e-con e-parent\" data-id=\"c7fcae4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13d2fd9 elementor-widget elementor-widget-text-editor\" data-id=\"13d2fd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Com mais de 10 anos de experi\u00eancia no setor, a Arik forneceu servi\u00e7os personalizados para mais de 64 clientes comerciais em todo o mundo. Nossos clientes incluem empresas de constru\u00e7\u00e3o, empreiteiras, atacadistas e distribuidores, com um \u00edndice de satisfa\u00e7\u00e3o do cliente de 95%. Temos o compromisso de oferecer solu\u00e7\u00f5es inovadoras que ajudam nossos clientes a se destacarem em um mercado competitivo.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2d80f297 e-transform e-flex e-con-boxed e-con e-parent\" data-id=\"2d80f297\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-0.90000000000000002220446049250313080847263336181640625,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_widescreen&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_laptop&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet_extra&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile_extra&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66dc3a19 axetor-scrolling-ltr elementor-widget elementor-widget-axetor-slide-scrolling\" data-id=\"66dc3a19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"axetor-slide-scrolling.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"elementor-scrolling\">\n                <div class=\"elementor-scrolling-wrapper\">\n                                            <div class=\"elementor-scrolling-inner\">\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-3f5e730\">\n                                            <a href=\"#\"  title=\"PRODU\u00c7\u00c3O SUSTENT\u00c1VEL\"><span>PRODU\u00c7\u00c3O SUSTENT\u00c1VEL<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-9621f68\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-2da5627\">\n                                            <a href=\"#\"  title=\"CADEIA DE SUPRIMENTOS EFICAZ\"><span>CADEIA DE SUPRIMENTOS EFICAZ<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-be74b8e\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-0162d60\">\n                                            <a href=\"#\"  title=\"personalizado\"><span>personalizado<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-e506f79\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-c0494ad\">\n                                            <a href=\"#\"  title=\"compras on-line\"><span>compras on-line<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-d33e758\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-6a87825\">\n                                            <a href=\"#\"  title=\"constru\u00eddo para o trabalho\"><span>constru\u00eddo para o trabalho<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-13cc1e7\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-127857f\">\n                                            <a href=\"#\"  title=\"SOCIALMENTE RESPONS\u00c1VEL\"><span>SOCIALMENTE RESPONS\u00c1VEL<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-1f593d3\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-aa66dc6\">\n                                            <a href=\"#\"  title=\"TOTALMENTE CONTROLADO\"><span>TOTALMENTE CONTROLADO<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-f3f0086\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                    <\/div>\n                                                <div class=\"elementor-scrolling-inner\">\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-3f5e730\">\n                                            <a href=\"#\"  title=\"PRODU\u00c7\u00c3O SUSTENT\u00c1VEL\"><span>PRODU\u00c7\u00c3O SUSTENT\u00c1VEL<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-9621f68\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-2da5627\">\n                                            <a href=\"#\"  title=\"CADEIA DE SUPRIMENTOS EFICAZ\"><span>CADEIA DE SUPRIMENTOS EFICAZ<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-be74b8e\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-0162d60\">\n                                            <a href=\"#\"  title=\"personalizado\"><span>personalizado<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-e506f79\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-c0494ad\">\n                                            <a href=\"#\"  title=\"compras on-line\"><span>compras on-line<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-d33e758\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-6a87825\">\n                                            <a href=\"#\"  title=\"constru\u00eddo para o trabalho\"><span>constru\u00eddo para o trabalho<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-13cc1e7\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-127857f\">\n                                            <a href=\"#\"  title=\"SOCIALMENTE RESPONS\u00c1VEL\"><span>SOCIALMENTE RESPONS\u00c1VEL<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-1f593d3\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-aa66dc6\">\n                                            <a href=\"#\"  title=\"TOTALMENTE CONTROLADO\"><span>TOTALMENTE CONTROLADO<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-f3f0086\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                    <\/div>\n                                                <div class=\"elementor-scrolling-inner\">\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-3f5e730\">\n                                            <a href=\"#\"  title=\"PRODU\u00c7\u00c3O SUSTENT\u00c1VEL\"><span>PRODU\u00c7\u00c3O SUSTENT\u00c1VEL<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-9621f68\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-2da5627\">\n                                            <a href=\"#\"  title=\"CADEIA DE SUPRIMENTOS EFICAZ\"><span>CADEIA DE SUPRIMENTOS EFICAZ<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-be74b8e\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-0162d60\">\n                                            <a href=\"#\"  title=\"personalizado\"><span>personalizado<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-e506f79\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-c0494ad\">\n                                            <a href=\"#\"  title=\"compras on-line\"><span>compras on-line<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-d33e758\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-6a87825\">\n                                            <a href=\"#\"  title=\"constru\u00eddo para o trabalho\"><span>constru\u00eddo para o trabalho<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-13cc1e7\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-127857f\">\n                                            <a href=\"#\"  title=\"SOCIALMENTE RESPONS\u00c1VEL\"><span>SOCIALMENTE RESPONS\u00c1VEL<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-1f593d3\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                <div class=\"scrolling-title elementor-repeater-item-aa66dc6\">\n                                            <a href=\"#\"  title=\"TOTALMENTE CONTROLADO\"><span>TOTALMENTE CONTROLADO<\/span><\/a>                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                            <div class=\"elementor-scrolling-item\">\n                                    <div class=\"elementor-scrolling-item-inner\">\n                                                                                    <img decoding=\"async\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2024\/01\/separate.svg\" title=\"separado\" alt=\"separado\" loading=\"lazy\" \/>                                                                                <div class=\"scrolling-title elementor-repeater-item-f3f0086\">\n                                                                                    <\/div>\n\n                                    <\/div>\n                                <\/div>\n                                                    <\/div>\n                                        <\/div>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67219577 e-con-full e-flex e-con e-parent\" data-id=\"67219577\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a9e1ac7 elementor-widget elementor-widget-heading\" data-id=\"5a9e1ac7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">O que nossos clientes dizem<\/h3>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-71ea3198 e-con-full e-flex e-con e-child\" data-id=\"71ea3198\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4850e7e7 e-con-full e-flex e-con e-child\" data-id=\"4850e7e7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-56534f60 elementor-widget elementor-widget-testimonial\" data-id=\"56534f60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">\"Trabalhar com a Arik aumentou significativamente nossa efici\u00eancia na constru\u00e7\u00e3o. Suas solu\u00e7\u00f5es personalizadas n\u00e3o apenas aumentaram a efic\u00e1cia operacional, mas tamb\u00e9m resolveram nossos problemas de desgaste de ferramentas de longa data.\"<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"287\" height=\"176\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/images.jpg\" class=\"attachment-full size-full wp-image-6362\" alt=\"\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Bechtel Corporation (EUA)<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c1e09b e-con-full e-flex e-con e-child\" data-id=\"1c1e09b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-160c85f6 elementor-widget elementor-widget-testimonial\" data-id=\"160c85f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">\"As solu\u00e7\u00f5es personalizadas da Arik eram exatamente o que precis\u00e1vamos para agilizar nosso processo de constru\u00e7\u00e3o. A durabilidade e o desempenho de seus produtos fizeram uma diferen\u00e7a real.\"<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"210\" height=\"232\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/portrait-asian-middle-aged-businessman-260nw-2356662917-1.webp\" class=\"attachment-full size-full wp-image-6364\" alt=\"\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\"> Shimizu Corporation (Jap\u00e3o)<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d92d3d3 e-con-full e-flex e-con e-child\" data-id=\"d92d3d3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-539e9384 elementor-widget elementor-widget-testimonial\" data-id=\"539e9384\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">\"As ferramentas inovadoras da Arik nos ajudaram a aumentar a velocidade e a seguran\u00e7a de nossos projetos. Seu profissionalismo e aten\u00e7\u00e3o aos detalhes s\u00e3o inigual\u00e1veis.\"<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/20190401031816201.jpg\" class=\"attachment-full size-full wp-image-6365\" alt=\"\" srcset=\"https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/20190401031816201.jpg 800w, https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/20190401031816201-300x200.jpg 300w, https:\/\/ariktools.com\/wp-content\/uploads\/2025\/01\/20190401031816201-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Hochtief AG (Alemanha)<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-298c59c5 e-flex e-con-boxed e-con e-parent\" data-id=\"298c59c5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-438b8896 elementor-widget elementor-widget-heading\" data-id=\"438b8896\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Experimente a excel\u00eancia da ARIK hoje mesmo!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cc307df elementor-widget elementor-widget-text-editor\" data-id=\"4cc307df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Seja voc\u00ea um empreiteiro comercial, uma empresa de constru\u00e7\u00e3o, um atacadista ou um gerente de canteiro de obras, escolher a Arik significa escolher solu\u00e7\u00f5es eficientes e personalizadas para seus projetos de constru\u00e7\u00e3o. Entre em contato conosco para saber mais ou obtenha um or\u00e7amento gratuito hoje mesmo para aumentar a efici\u00eancia do seu projeto\uff01<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-411a77ff elementor-mobile-align-center elementor-align-center elementor-button-default elementor-widget elementor-widget-button\" data-id=\"411a77ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ariktools.com\/pt\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicite uma cota\u00e7\u00e3o agora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2034596f e-flex e-con-boxed e-con e-parent\" data-id=\"2034596f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3397e638 title-gradient-yes elementor-absolute elementor-widget elementor-widget-heading\" data-id=\"3397e638\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">do blog<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22907f99 elementor-widget elementor-widget-heading\" data-id=\"22907f99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00faltima publica\u00e7\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75b0a13c disable-excerpt-yes overflow-to-none elementor-widget elementor-widget-axetor-post-grid\" data-id=\"75b0a13c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;slides_to_show_laptop&quot;:&quot;3&quot;,&quot;slides_to_show_tablet_extra&quot;:&quot;3&quot;,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile_extra&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1.2&quot;,&quot;spaceBetween_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;spaceBetween_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;spaceBetween_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;spaceBetween_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;spaceBetween_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;spaceBetween&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;spaceBetween_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;swiper_overflow&quot;:&quot;none&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;enable_scrollbar&quot;:&quot;no&quot;,&quot;allowTouchMove&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"axetor-post-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-post-wrapper axetor-swiper swiper-container\" dir=\"ltr\">\n            <div class=\"swiper-wrapper\">\n\n                                    <div class=\"grid-item swiper-slide\">\n                        <div class=\"post-inner blog-grid\">\n        <div class=\"post-content\">\n        <div class=\"entry-meta\">\n             <div class=\"categories-link\"><span class=\"screen-reader-text\">Categorias<\/span><a href=\"https:\/\/ariktools.com\/pt\/blog-category\/all-post\/\" rel=\"category tag\">Todas as postagens<\/a><\/div> <div class=\"posted-on\"><a href=\"https:\/\/ariktools.com\/pt\/german-client-case-how-we-planned-every-step-ahead\/\" rel=\"bookmark\"><time class=\"entry-date published\" datetime=\"2025-10-30T17:17:52+00:00\">30 de outubro de 2025<\/time><time class=\"updated\" datetime=\"2025-10-30T17:20:50+00:00\">30 de outubro de 2025<\/time><\/a><\/div>         <\/div>\n        <h3 class=\"omega entry-title\"><a href=\"https:\/\/ariktools.com\/pt\/german-client-case-how-we-planned-every-step-ahead\/\" rel=\"bookmark\">Caso de cliente alem\u00e3o: como planejamos cada passo \u00e0 frente<\/a><\/h3>    <\/div>\n<\/div>                    <\/div>\n                                        <div class=\"grid-item swiper-slide\">\n                        <div class=\"post-inner blog-grid\">\n        <div class=\"post-content\">\n        <div class=\"entry-meta\">\n             <div class=\"categories-link\"><span class=\"screen-reader-text\">Categorias<\/span><a href=\"https:\/\/ariktools.com\/pt\/blog-category\/all-post\/\" rel=\"category tag\">Todas as postagens<\/a><\/div> <div class=\"posted-on\"><a href=\"https:\/\/ariktools.com\/pt\/floor-rollers-in-vinyl-flooring-why-they-matter-and-how-to-choose-the-right-ones\/\" rel=\"bookmark\"><time class=\"entry-date published\" datetime=\"2025-10-29T17:01:39+00:00\">outubro 29, 2025<\/time><time class=\"updated\" datetime=\"2025-10-29T17:02:58+00:00\">outubro 29, 2025<\/time><\/a><\/div>         <\/div>\n        <h3 class=\"omega entry-title\"><a href=\"https:\/\/ariktools.com\/pt\/floor-rollers-in-vinyl-flooring-why-they-matter-and-how-to-choose-the-right-ones\/\" rel=\"bookmark\">Rolos de piso em pisos de vinil: Por que eles s\u00e3o importantes e como escolher os corretos<\/a><\/h3>    <\/div>\n<\/div>                    <\/div>\n                                        <div class=\"grid-item swiper-slide\">\n                        <div class=\"post-inner blog-grid\">\n        <div class=\"post-content\">\n        <div class=\"entry-meta\">\n             <div class=\"categories-link\"><span class=\"screen-reader-text\">Categorias<\/span><a href=\"https:\/\/ariktools.com\/pt\/blog-category\/all-post\/\" rel=\"category tag\">Todas as postagens<\/a><\/div> <div class=\"posted-on\"><a href=\"https:\/\/ariktools.com\/pt\/how-to-bulk-buy-vinyl-flooring-tools-without-wasting-money-or-time\/\" rel=\"bookmark\"><time class=\"entry-date published\" datetime=\"2025-10-29T16:57:48+00:00\">outubro 29, 2025<\/time><time class=\"updated\" datetime=\"2025-10-29T17:01:25+00:00\">outubro 29, 2025<\/time><\/a><\/div>         <\/div>\n        <h3 class=\"omega entry-title\"><a href=\"https:\/\/ariktools.com\/pt\/how-to-bulk-buy-vinyl-flooring-tools-without-wasting-money-or-time\/\" rel=\"bookmark\">Como comprar ferramentas para pisos de vinil em grande quantidade (sem perder tempo ou dinheiro)<\/a><\/h3>    <\/div>\n<\/div>                    <\/div>\n                                <\/div>\n\n                    <\/div>\n                        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46f61fc0 elementor-button-outline show-effect-yes elementor-widget elementor-widget-button\" data-id=\"46f61fc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ariktools.com\/pt\/blog-category\/success-project\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"axetor-icon- axetor-icon-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ver todas as postagens<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Como fabricante l\u00edder no setor de ferramentas, a Arik \u00e9 especializada em fornecer solu\u00e7\u00f5es personalizadas e de alta qualidade para o setor da constru\u00e7\u00e3o civil, empresas de instala\u00e7\u00e3o de pisos e atacadistas. Compreendemos os desafios espec\u00edficos de cada projeto e colocamos sempre as necessidades do cliente em primeiro lugar, fornecendo as ferramentas e os servi\u00e7os mais adequados para cada obra. Seja qual for a sua necessidade, desde [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6116","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ariktools.com\/pt\/wp-json\/wp\/v2\/pages\/6116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ariktools.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ariktools.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ariktools.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ariktools.com\/pt\/wp-json\/wp\/v2\/comments?post=6116"}],"version-history":[{"count":0,"href":"https:\/\/ariktools.com\/pt\/wp-json\/wp\/v2\/pages\/6116\/revisions"}],"wp:attachment":[{"href":"https:\/\/ariktools.com\/pt\/wp-json\/wp\/v2\/media?parent=6116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}